{"id":9040,"date":"2017-09-18T08:34:54","date_gmt":"2017-09-18T08:34:54","guid":{"rendered":"http:\/\/www.namespick.com\/muslim-names\/?p=9040"},"modified":"2018-12-25T14:59:04","modified_gmt":"2018-12-25T14:59:04","slug":"jummal","status":"publish","type":"post","link":"https:\/\/www.namespick.com\/muslim-names\/jummal\/","title":{"rendered":"Jummal"},"content":{"rendered":"<p><strong>&nbsp;<\/strong>A thick rope, a rope with which a boat is anchored.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;A thick rope, a rope with which a boat is anchored.<\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jummal - Muslim Names<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.namespick.com\/muslim-names\/jummal\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jummal - Muslim Names\" \/>\n<meta property=\"og:description\" content=\"&nbsp;A thick rope, a rope with which a boat is anchored.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.namespick.com\/muslim-names\/jummal\/\" \/>\n<meta property=\"og:site_name\" content=\"Muslim Names\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/NamesPick\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-18T08:34:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-25T14:59:04+00:00\" \/>\n<meta name=\"author\" content=\"namespick\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@namespick\" \/>\n<meta name=\"twitter:site\" content=\"@namespick\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"namespick\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.namespick.com\/muslim-names\/jummal\/\",\"url\":\"https:\/\/www.namespick.com\/muslim-names\/jummal\/\",\"name\":\"Jummal - Muslim Names\",\"isPartOf\":{\"@id\":\"https:\/\/www.namespick.com\/muslim-names\/#website\"},\"datePublished\":\"2017-09-18T08:34:54+00:00\",\"dateModified\":\"2018-12-25T14:59:04+00:00\",\"author\":{\"@id\":\"https:\/\/www.namespick.com\/muslim-names\/#\/schema\/person\/cb8ad4fa16d589a50aa48dc3df7c5b9d\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.namespick.com\/muslim-names\/jummal\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.namespick.com\/muslim-names\/jummal\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.namespick.com\/muslim-names\/jummal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.namespick.com\/muslim-names\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jummal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.namespick.com\/muslim-names\/#website\",\"url\":\"https:\/\/www.namespick.com\/muslim-names\/\",\"name\":\"Namespick - Muslim Names\",\"description\":\"Names Pick\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.namespick.com\/muslim-names\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.namespick.com\/muslim-names\/#\/schema\/person\/cb8ad4fa16d589a50aa48dc3df7c5b9d\",\"name\":\"namespick\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.namespick.com\/muslim-names\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/45799d23473d87268e9d523fd3f037d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/45799d23473d87268e9d523fd3f037d4?s=96&d=mm&r=g\",\"caption\":\"namespick\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jummal - Muslim Names","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.namespick.com\/muslim-names\/jummal\/","og_locale":"en_US","og_type":"article","og_title":"Jummal - Muslim Names","og_description":"&nbsp;A thick rope, a rope with which a boat is anchored.","og_url":"https:\/\/www.namespick.com\/muslim-names\/jummal\/","og_site_name":"Muslim Names","article_publisher":"https:\/\/www.facebook.com\/NamesPick\/","article_published_time":"2017-09-18T08:34:54+00:00","article_modified_time":"2018-12-25T14:59:04+00:00","author":"namespick","twitter_card":"summary_large_image","twitter_creator":"@namespick","twitter_site":"@namespick","twitter_misc":{"Written by":"namespick"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.namespick.com\/muslim-names\/jummal\/","url":"https:\/\/www.namespick.com\/muslim-names\/jummal\/","name":"Jummal - Muslim Names","isPartOf":{"@id":"https:\/\/www.namespick.com\/muslim-names\/#website"},"datePublished":"2017-09-18T08:34:54+00:00","dateModified":"2018-12-25T14:59:04+00:00","author":{"@id":"https:\/\/www.namespick.com\/muslim-names\/#\/schema\/person\/cb8ad4fa16d589a50aa48dc3df7c5b9d"},"breadcrumb":{"@id":"https:\/\/www.namespick.com\/muslim-names\/jummal\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.namespick.com\/muslim-names\/jummal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.namespick.com\/muslim-names\/jummal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.namespick.com\/muslim-names\/"},{"@type":"ListItem","position":2,"name":"Jummal"}]},{"@type":"WebSite","@id":"https:\/\/www.namespick.com\/muslim-names\/#website","url":"https:\/\/www.namespick.com\/muslim-names\/","name":"Namespick - Muslim Names","description":"Names Pick","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.namespick.com\/muslim-names\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.namespick.com\/muslim-names\/#\/schema\/person\/cb8ad4fa16d589a50aa48dc3df7c5b9d","name":"namespick","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.namespick.com\/muslim-names\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/45799d23473d87268e9d523fd3f037d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45799d23473d87268e9d523fd3f037d4?s=96&d=mm&r=g","caption":"namespick"}}]}},"_links":{"self":[{"href":"https:\/\/www.namespick.com\/muslim-names\/wp-json\/wp\/v2\/posts\/9040"}],"collection":[{"href":"https:\/\/www.namespick.com\/muslim-names\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.namespick.com\/muslim-names\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.namespick.com\/muslim-names\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.namespick.com\/muslim-names\/wp-json\/wp\/v2\/comments?post=9040"}],"version-history":[{"count":0,"href":"https:\/\/www.namespick.com\/muslim-names\/wp-json\/wp\/v2\/posts\/9040\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.namespick.com\/muslim-names\/wp-json\/wp\/v2\/media?parent=9040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}